{"id":7024,"date":"2018-08-27T09:23:18","date_gmt":"2018-08-27T09:23:18","guid":{"rendered":"https:\/\/start.cargoclix.com\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/"},"modified":"2018-09-13T18:45:31","modified_gmt":"2018-09-13T18:45:31","slug":"allegati-ottimizzati-per-i-fornitori-di-servizi","status":"publish","type":"post","link":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/","title":{"rendered":"Allegati ottimizzati per i fornitori di servizi"},"content":{"rendered":"<p>Una visualizzazione ottimizzata fornisce informazioni dettagliate sugli allegati dei fornitori di servizi.<br \/>\nAd esempio, se un fornitore di servizi logistici carica documenti al momento della prenotazione degli slot, gli operatori del sito possono visualizzare la data e l&#8217;ora di pubblicazione di ogni allegato.<br \/>\nIl documento viene visualizzato come collegamento e pu\u00f2 essere aperto con un semplice clic del mouse. Per evitare l&#8217;eliminazione accidentale degli allegati, il pulsante \u201cEliminare\u201d viene visualizzato pi\u00f9 lontano ed \u00e8 integrata anche una richiesta di conferma.<br \/>\nOttimizzare gli allegati del fornitore di servizi:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una visualizzazione ottimizzata fornisce informazioni dettagliate sugli allegati dei fornitori di servizi. Ad esempio, se un fornitore di servizi logistici carica documenti al momento della prenotazione degli slot, gli operatori del sito possono visualizzare la data e l&#8217;ora di pubblicazione di ogni allegato. Il documento viene visualizzato come collegamento e pu\u00f2 essere aperto con un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[308],"tags":[263,267],"class_list":["post-7024","post","type-post","status-publish","format-standard","hentry","category-tech-news-it","tag-slot-2-de-it","tag-tech-news-2-de-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allegati ottimizzati per i fornitori di servizi - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allegati ottimizzati per i fornitori di servizi - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Una visualizzazione ottimizzata fornisce informazioni dettagliate sugli allegati dei fornitori di servizi. Ad esempio, se un fornitore di servizi logistici carica documenti al momento della prenotazione degli slot, gli operatori del sito possono visualizzare la data e l&#8217;ora di pubblicazione di ogni allegato. Il documento viene visualizzato come collegamento e pu\u00f2 essere aperto con un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-27T09:23:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-13T18:45:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Allegati ottimizzati per i fornitori di servizi\",\"datePublished\":\"2018-08-27T09:23:18+00:00\",\"dateModified\":\"2018-09-13T18:45:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/\"},\"wordCount\":93,\"publisher\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\"},\"keywords\":[\"SLOT\",\"TECH NEWS\"],\"articleSection\":[\"TECH News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/\",\"url\":\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/\",\"name\":\"Allegati ottimizzati per i fornitori di servizi - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#website\"},\"datePublished\":\"2018-08-27T09:23:18+00:00\",\"dateModified\":\"2018-09-13T18:45:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/start.cargoclix.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TECH News\",\"item\":\"https:\/\/start.cargoclix.com\/it\/category\/tech-news-it\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Allegati ottimizzati per i fornitori di servizi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#website\",\"url\":\"https:\/\/start.cargoclix.com\/ru\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/start.cargoclix.com\/ru\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/start.cargoclix.com\/ru\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/start.cargoclix.com\/it\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allegati ottimizzati per i fornitori di servizi - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/","og_locale":"it_IT","og_type":"article","og_title":"Allegati ottimizzati per i fornitori di servizi - Cargoclix","og_description":"Una visualizzazione ottimizzata fornisce informazioni dettagliate sugli allegati dei fornitori di servizi. Ad esempio, se un fornitore di servizi logistici carica documenti al momento della prenotazione degli slot, gli operatori del sito possono visualizzare la data e l&#8217;ora di pubblicazione di ogni allegato. Il documento viene visualizzato come collegamento e pu\u00f2 essere aperto con un [&hellip;]","og_url":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2018-08-27T09:23:18+00:00","article_modified_time":"2018-09-13T18:45:31+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"websitedev"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/#article","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/"},"author":{"name":"websitedev","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Allegati ottimizzati per i fornitori di servizi","datePublished":"2018-08-27T09:23:18+00:00","dateModified":"2018-09-13T18:45:31+00:00","mainEntityOfPage":{"@id":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/"},"wordCount":93,"publisher":{"@id":"https:\/\/start.cargoclix.com\/ru\/#organization"},"keywords":["SLOT","TECH NEWS"],"articleSection":["TECH News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/","url":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/","name":"Allegati ottimizzati per i fornitori di servizi - Cargoclix","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/ru\/#website"},"datePublished":"2018-08-27T09:23:18+00:00","dateModified":"2018-09-13T18:45:31+00:00","breadcrumb":{"@id":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/start.cargoclix.com\/it\/2018\/08\/27\/allegati-ottimizzati-per-i-fornitori-di-servizi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/start.cargoclix.com\/it\/"},{"@type":"ListItem","position":2,"name":"TECH News","item":"https:\/\/start.cargoclix.com\/it\/category\/tech-news-it\/"},{"@type":"ListItem","position":3,"name":"Allegati ottimizzati per i fornitori di servizi"}]},{"@type":"WebSite","@id":"https:\/\/start.cargoclix.com\/ru\/#website","url":"https:\/\/start.cargoclix.com\/ru\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/start.cargoclix.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/start.cargoclix.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/start.cargoclix.com\/ru\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/start.cargoclix.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/start.cargoclix.com\/it\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/posts\/7024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/comments?post=7024"}],"version-history":[{"count":1,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/posts\/7024\/revisions"}],"predecessor-version":[{"id":7028,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/posts\/7024\/revisions\/7028"}],"wp:attachment":[{"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/media?parent=7024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/categories?post=7024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/tags?post=7024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}