{"id":18028,"date":"2022-03-02T10:36:44","date_gmt":"2022-03-02T10:36:44","guid":{"rendered":"https:\/\/start.cargoclix.com\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/"},"modified":"2022-04-12T12:16:50","modified_gmt":"2022-04-12T12:16:50","slug":"anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica","status":"publish","type":"post","link":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/","title":{"rendered":"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica"},"content":{"rendered":"<div id=\"attachment_18014\" style=\"width: 1010px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-18014\" class=\"wp-image-18014 size-full\" src=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg\" alt=\"Mit einer neuen App will Cargoclix Lieferketten k\u00fcnftig noch effizienter machen. Prof. Dr. Victor Meier, beratender Gesellschafter bei Cargoclix, k\u00fcndigt Details zum Angebot rechtzeitig zur Messe an. (Foto: AdobeStock)\" width=\"1000\" height=\"500\" srcset=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg 1000w, https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1-300x150.jpeg 300w, https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1-768x384.jpeg 768w, https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1-500x250.jpeg 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><p id=\"caption-attachment-18014\" class=\"wp-caption-text\"><span style=\"font-weight: 400;\">Con una nuova applicazione, Cargoclix desidera rendere ancora pi\u00f9 efficienti la gestione delle catene logistiche in futuro. Il Prof. Dr. Victor Meier, socio di consulenza di Cargoclix, fornisce dettagli anticipati sull&#8217;offerta che verr\u00e0 presentata alla fiera. (Foto: AdobeStock)<\/span><\/p><\/div>\n<ul>\n<li><em><strong>Il produttore di software di Friburgo presenta per la prima volta una nuova applicazione che consente una comunicazione senza discontinuit\u00e0 mediatica tra l\u2019operatore del sito e l\u2019autista.\u00a0<\/strong><\/em><\/li>\n<li><em><strong>Registrazione immediata e diretta di tutte le informazioni rilevanti relative al processo in tempo reale.<\/strong><\/em><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">(Friburgo i.Br., 22 febbraio, 2022) Il produttore di software di Friburgo in Brisgovia, Cargoclix presenta un\u2019anteprima mondiale alla fiera intralogistica di Stoccarda LogiMAT 2022 dal 31 maggio al 2 giugno. Presso il padiglione 6, stand F60, Cargoclix presenter\u00e0 per la prima volta un&#8217;applicazione all&#8217;avanguardia che consente una comunicazione senza discontinuit\u00e0 mediatica tra tutte le persone coinvolte nel processo di consegna e di conseguenza rende i processi presso la rampa ancora pi\u00f9 efficienti. &#8220;La nostra ultima applicazione innovativa, che pu\u00f2 essere direttamente collegata al nostro sistema informatico collaudato <\/span><i><span style=\"font-weight: 400;\">SLOT<\/span><\/i><span style=\"font-weight: 400;\"> oppure utilizzata anche come soluzione indipendente, consente una comunicazione diretta tra il magazzino o la sede logistica e l&#8217;autista&#8221;: dice il Prof. Dr. Victor Meier, socio di consulenza di Cargoclix. L\u2019applicazione garantisce una registrazione immediata e diretta di tutte le informazioni rilevanti relative al processo di consegna in tempo reale. Ulteriori dettagli sull&#8217;applicazione saranno forniti poco prima del LogiMAT.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nel suo bagaglio fieristico l&#8217;azienda ha anche alcuni prodotti gi\u00e0 collaudati. Cargoclix presenter\u00e0 ulteriormente i suoi due prodotti di punta a Stoccarda: Il sistema informatico <\/span><i><span style=\"font-weight: 400;\">SLOT<\/span><\/i><span style=\"font-weight: 400;\"> e la sua piattaforma logistica <\/span><i><span style=\"font-weight: 400;\">TENDER<\/span><\/i><span style=\"font-weight: 400;\">, che \u00e8 una delle principali piattaforme internazionali per i contratti di trasporto e logistica. Con il costo di 0,50 euro a prenotazione, <\/span><i><span style=\"font-weight: 400;\">SLOT<\/span><\/i><span style=\"font-weight: 400;\"> continua ad essere uno dei sistemi informatici di gestione delle fasce orarie pi\u00f9 convenienti ed allo stesso tempo pi\u00f9 potenti, utilizzati dai fornitori di servizi logistici, cos\u00ec come nell&#8217;industria e nel commercio in tutti i settori.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il sistema informatico modulabile <\/span><i><span style=\"font-weight: 400;\">SLOT<\/span><\/i><span style=\"font-weight: 400;\">, che pu\u00f2 essere utilizzato sia come soluzione indipendente che completamente integrato nei sistemi ERP e WMS, ha recentemente registrato un enorme aumento del numero degli utenti. &#8220;A causa della pandemia Covid e di una conseguente maggiore necessit\u00e0 di catene logistiche organizzate in modo stabile, il numero dei nostri utenti ha subito un aumento di oltre il 53% dal febbraio 2020 alla fine del 2021 e recentemente ha superato la soglia dei 100.000&#8221;: continua Meier. Il sistema attualmente \u00e8 in uso presso circa 1.800 sedi dei clienti e le sue funzionalit\u00e0 vengono costantemente sviluppate e adattate. Ad esempio, ora il sistema offre agli operatori di rampa la possibilit\u00e0 di informare i fornitori di servizi logistici e gli autisti di camion direttamente tramite la piattaforma sui regolamenti e sulle regole Covid applicabili presso la rispettiva sede.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La piattaforma informatica <\/span><i><span style=\"font-weight: 400;\">TENDER<\/span><\/i><span style=\"font-weight: 400;\">, che permette gare d\u2019appalto a livello mondiale per il trasporto stradale, ferroviario, aereo, merci, marittimo e fluviale, servizi di corriere espresso e servizi logistici come il magazzinaggio, \u00e8 caratterizzato soprattutto dal suo uso intuitivo. &#8220;Con tale soluzione, desideriamo mettere a disposizione dei nostri clienti un tool con il quale possono realizzare in modo intuitivo anche gare d&#8217;appalto semplici e di piccoli volumi &#8220;: sottolinea Meier. Tra l\u2019altro, <\/span><i><span style=\"font-weight: 400;\">TENDER<\/span><\/i><span style=\"font-weight: 400;\"> lavora con un modello di prezzi favorevole e flessibile e ha una copertura molto ampia ed alta attraverso una grande rete di spedizionieri e vettori collegati. <\/span><\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-17783 alignright\" src=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2021\/12\/Victor-Meier-1000x667-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2021\/12\/Victor-Meier-1000x667-1-300x200.jpg 300w, https:\/\/start.cargoclix.com\/wp-content\/uploads\/2021\/12\/Victor-Meier-1000x667-1-768x512.jpg 768w, https:\/\/start.cargoclix.com\/wp-content\/uploads\/2021\/12\/Victor-Meier-1000x667-1-500x333.jpg 500w, https:\/\/start.cargoclix.com\/wp-content\/uploads\/2021\/12\/Victor-Meier-1000x667-1.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>Informazioni su Cargoclix<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix \u00e8 una piattaforma informatica neutrale per i tender di trasporti e servizi logistici ed \u00e8 un fornitore di sistemi modulari di gestione delle fasce orarie.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La piattaforma logistica \u201cCargoclix <\/span><i><span style=\"font-weight: 400;\">TENDER<\/span><\/i><span style=\"font-weight: 400;\">\u201d offre tender a livello internazionale per contratti di trasporto stradale, ferroviario, aereo, marittimo e fluviale, servizi di corriere espresso e servizi logistici come il magazzinaggio. Con oltre 28.000 utenti registrati dell\u2019industria, del commercio e delle spedizioni, <\/span><i><span style=\"font-weight: 400;\">TENDER <\/span><\/i><span style=\"font-weight: 400;\">\u00e8 una delle principali piattaforme internazionali di gare d\u2019appalto per il trasporto e la logistica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il prodotto principale per la gestione delle fasce orarie \u00e8 il software modulare adattabile \u201cCargoclix <\/span><i><span style=\"font-weight: 400;\">SLOT<\/span><\/i><span style=\"font-weight: 400;\">\u201d per l\u2019ottimizzazione dei processi sulla rampa. Con pi\u00f9 di 100.000 utenti, <\/span><i><span style=\"font-weight: 400;\">SLOT <\/span><\/i><span style=\"font-weight: 400;\">\u00e8 uno dei sistemi informatici di gestione delle fasce orarie pi\u00f9 utilizzati e comuni.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix \u00e8 una marca di Dr. Meier &amp; Schmidt GmbH. L\u2019azienda \u00e8 stata fondata nel 1998 ed ha la sua sede a Friburgo i.Br.<\/span><a href=\"http:\/\/www.cargoclix.com\/\"> <span style=\"font-weight: 400;\">www.cargoclix.com<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il produttore di software di Friburgo presenta per la prima volta una nuova applicazione che consente una comunicazione senza discontinuit\u00e0 mediatica tra l\u2019operatore del sito e l\u2019autista.\u00a0 Registrazione immediata e diretta di tutte le informazioni rilevanti relative al processo in tempo reale. (Friburgo i.Br., 22 febbraio, 2022) Il produttore di software di Friburgo in Brisgovia, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[326],"tags":[],"class_list":["post-18028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica - Cargoclix<\/title>\n<meta name=\"description\" content=\"Il produttore di software Cargoclix presenta un\u2019anteprima mondiale alla LogiMAT 2022 dal 31 maggio al 2 giugno\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Il produttore di software Cargoclix presenta un\u2019anteprima mondiale alla LogiMAT 2022 dal 31 maggio al 2 giugno\" \/>\n<meta property=\"og:url\" content=\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-02T10:36:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-12T12:16:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica\",\"datePublished\":\"2022-03-02T10:36:44+00:00\",\"dateModified\":\"2022-04-12T12:16:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/\"},\"wordCount\":723,\"publisher\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg\",\"articleSection\":[\"Press Releases\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/\",\"url\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/\",\"name\":\"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg\",\"datePublished\":\"2022-03-02T10:36:44+00:00\",\"dateModified\":\"2022-04-12T12:16:50+00:00\",\"description\":\"Il produttore di software Cargoclix presenta un\u2019anteprima mondiale alla LogiMAT 2022 dal 31 maggio al 2 giugno\",\"breadcrumb\":{\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#primaryimage\",\"url\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg\",\"contentUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg\",\"width\":1000,\"height\":500,\"caption\":\"Aerial view of logistic center\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/start.cargoclix.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Releases\",\"item\":\"https:\/\/start.cargoclix.com\/de\/category\/press-releases-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#website\",\"url\":\"https:\/\/start.cargoclix.com\/ru\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/start.cargoclix.com\/ru\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/start.cargoclix.com\/ru\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/start.cargoclix.com\/it\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica - Cargoclix","description":"Il produttore di software Cargoclix presenta un\u2019anteprima mondiale alla LogiMAT 2022 dal 31 maggio al 2 giugno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/","og_locale":"it_IT","og_type":"article","og_title":"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica - Cargoclix","og_description":"Il produttore di software Cargoclix presenta un\u2019anteprima mondiale alla LogiMAT 2022 dal 31 maggio al 2 giugno","og_url":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2022-03-02T10:36:44+00:00","article_modified_time":"2022-04-12T12:16:50+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg","type":"image\/jpeg"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"websitedev","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#article","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/"},"author":{"name":"websitedev","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica","datePublished":"2022-03-02T10:36:44+00:00","dateModified":"2022-04-12T12:16:50+00:00","mainEntityOfPage":{"@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/"},"wordCount":723,"publisher":{"@id":"https:\/\/start.cargoclix.com\/ru\/#organization"},"image":{"@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg","articleSection":["Press Releases"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/","url":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/","name":"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica - Cargoclix","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#primaryimage"},"image":{"@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg","datePublished":"2022-03-02T10:36:44+00:00","dateModified":"2022-04-12T12:16:50+00:00","description":"Il produttore di software Cargoclix presenta un\u2019anteprima mondiale alla LogiMAT 2022 dal 31 maggio al 2 giugno","breadcrumb":{"@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#primaryimage","url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg","contentUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2022\/02\/AdobeStock_169953685-1.jpeg","width":1000,"height":500,"caption":"Aerial view of logistic center"},{"@type":"BreadcrumbList","@id":"https:\/\/start.cargoclix.com\/it\/2022\/03\/02\/anteprima-mondiale-alla-fiera-logimat-2022-cargoclix-presenta-la-nuova-applicazione-per-una-gestione-piu-efficiente-dei-processi-della-catena-logistica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/start.cargoclix.com\/it\/"},{"@type":"ListItem","position":2,"name":"Press Releases","item":"https:\/\/start.cargoclix.com\/de\/category\/press-releases-de\/"},{"@type":"ListItem","position":3,"name":"Anteprima mondiale alla fiera LogiMAT 2022: Cargoclix presenta la nuova applicazione per una gestione pi\u00f9 efficiente dei processi della catena logistica"}]},{"@type":"WebSite","@id":"https:\/\/start.cargoclix.com\/ru\/#website","url":"https:\/\/start.cargoclix.com\/ru\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/start.cargoclix.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/start.cargoclix.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/start.cargoclix.com\/ru\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/start.cargoclix.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/start.cargoclix.com\/it\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/posts\/18028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/comments?post=18028"}],"version-history":[{"count":1,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/posts\/18028\/revisions"}],"predecessor-version":[{"id":18223,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/posts\/18028\/revisions\/18223"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/media\/18017"}],"wp:attachment":[{"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/media?parent=18028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/categories?post=18028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/start.cargoclix.com\/it\/wp-json\/wp\/v2\/tags?post=18028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}