{"id":8026,"date":"2018-11-09T12:25:11","date_gmt":"2018-11-09T12:25:11","guid":{"rendered":"https:\/\/start.cargoclix.com\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/"},"modified":"2018-11-09T12:25:11","modified_gmt":"2018-11-09T12:25:11","slug":"copiar-campo-de-datos-de-reserva","status":"publish","type":"post","link":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/","title":{"rendered":"Copiar campo de datos de reserva"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Adem\u00e1s de copiar rampas completas, los ajustes de un campo de datos de reserva configurado una vez tambi\u00e9n se pueden utilizar para otras rampas. De este modo, los CargoMarketes existentes pueden redise\u00f1arse de forma r\u00e1pida y flexible seg\u00fan sea necesario. Especialmente para lugares con muchas rampas, los ajustes se pueden hacer f\u00e1cil y r\u00e1pidamente con s\u00f3lo unos pocos clics.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta opci\u00f3n es \u00fatil si, por ejemplo, un operador de rampa desea ajustar la configuraci\u00f3n de sus rampas o corregir errores como resultado de cambios en el proceso. Para ello, el ajuste deseado se implementa como un campo de datos de reserva en una rampa y se adopta la configuraci\u00f3n para todo el CargoMarket. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Copiar campos de datos de reserva:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los campos de datos de reserva pueden ser copiados por el administrador de Cargomarket:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mi CCX &gt; Franjas horarias &gt; Datos de reserva (se muestra un s\u00edmbolo de copia por rampa<\/span><\/p>\n<p><span style=\"font-weight: 400;\">) &gt; Haga clic en el s\u00edmbolo Copiar &gt; Seleccione si desea copiar todo el campo o s\u00f3lo una configuraci\u00f3n \u00fanica &gt; Seleccione en qu\u00e9 rampas se debe copiar el campo.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de copiar rampas completas, los ajustes de un campo de datos de reserva configurado una vez tambi\u00e9n se pueden utilizar para otras rampas. De este modo, los CargoMarketes existentes pueden redise\u00f1arse de forma r\u00e1pida y flexible seg\u00fan sea necesario. Especialmente para lugares con muchas rampas, los ajustes se pueden hacer f\u00e1cil y r\u00e1pidamente con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[309],"tags":[335,334],"class_list":["post-8026","post","type-post","status-publish","format-standard","hentry","category-tech-news-es","tag-slot","tag-tech-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Copiar campo de datos de reserva - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Copiar campo de datos de reserva - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s de copiar rampas completas, los ajustes de un campo de datos de reserva configurado una vez tambi\u00e9n se pueden utilizar para otras rampas. De este modo, los CargoMarketes existentes pueden redise\u00f1arse de forma r\u00e1pida y flexible seg\u00fan sea necesario. Especialmente para lugares con muchas rampas, los ajustes se pueden hacer f\u00e1cil y r\u00e1pidamente con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-09T12:25:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/02\/ccx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"746\" \/>\n\t<meta property=\"og:image:height\" content=\"746\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"Copiar campo de datos de reserva\",\"datePublished\":\"2018-11-09T12:25:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/\"},\"wordCount\":202,\"publisher\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\"},\"keywords\":[\"SLOT\",\"TECH NEWS\"],\"articleSection\":[\"TECH News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/\",\"url\":\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/\",\"name\":\"Copiar campo de datos de reserva - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#website\"},\"datePublished\":\"2018-11-09T12:25:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/start.cargoclix.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TECH News\",\"item\":\"https:\/\/start.cargoclix.com\/es\/category\/tech-news-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Copiar campo de datos de reserva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#website\",\"url\":\"https:\/\/start.cargoclix.com\/ru\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/start.cargoclix.com\/ru\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/start.cargoclix.com\/ru\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/start.cargoclix.com\/es\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Copiar campo de datos de reserva - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/","og_locale":"es_ES","og_type":"article","og_title":"Copiar campo de datos de reserva - Cargoclix","og_description":"Adem\u00e1s de copiar rampas completas, los ajustes de un campo de datos de reserva configurado una vez tambi\u00e9n se pueden utilizar para otras rampas. De este modo, los CargoMarketes existentes pueden redise\u00f1arse de forma r\u00e1pida y flexible seg\u00fan sea necesario. Especialmente para lugares con muchas rampas, los ajustes se pueden hacer f\u00e1cil y r\u00e1pidamente con [&hellip;]","og_url":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2018-11-09T12:25:11+00:00","og_image":[{"width":746,"height":746,"url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/02\/ccx2.png","type":"image\/png"}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"websitedev","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/#article","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/"},"author":{"name":"websitedev","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"Copiar campo de datos de reserva","datePublished":"2018-11-09T12:25:11+00:00","mainEntityOfPage":{"@id":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/"},"wordCount":202,"publisher":{"@id":"https:\/\/start.cargoclix.com\/ru\/#organization"},"keywords":["SLOT","TECH NEWS"],"articleSection":["TECH News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/","url":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/","name":"Copiar campo de datos de reserva - Cargoclix","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/ru\/#website"},"datePublished":"2018-11-09T12:25:11+00:00","breadcrumb":{"@id":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/start.cargoclix.com\/es\/2018\/11\/09\/copiar-campo-de-datos-de-reserva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/start.cargoclix.com\/es\/"},{"@type":"ListItem","position":2,"name":"TECH News","item":"https:\/\/start.cargoclix.com\/es\/category\/tech-news-es\/"},{"@type":"ListItem","position":3,"name":"Copiar campo de datos de reserva"}]},{"@type":"WebSite","@id":"https:\/\/start.cargoclix.com\/ru\/#website","url":"https:\/\/start.cargoclix.com\/ru\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/start.cargoclix.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/start.cargoclix.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/start.cargoclix.com\/ru\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/start.cargoclix.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/start.cargoclix.com\/es\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/posts\/8026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/comments?post=8026"}],"version-history":[{"count":0,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/posts\/8026\/revisions"}],"wp:attachment":[{"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/media?parent=8026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/categories?post=8026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/tags?post=8026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}