{"id":10365,"date":"2019-09-25T10:07:40","date_gmt":"2019-09-25T10:07:40","guid":{"rendered":"https:\/\/start.cargoclix.com\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/"},"modified":"2019-09-25T10:07:40","modified_gmt":"2019-09-25T10:07:40","slug":"el-mayorista-d-f-liedelt-presenta-slot","status":"publish","type":"post","link":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/","title":{"rendered":"El mayorista D. F. Liedelt presenta SLOT"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.andreaspaulsen.de\" target=\"_blank\" rel=\"noopener noreferrer\">D.F. Liedelt Heizungs- und Sanit\u00e4r Gro\u00dfhandels-GmbH<\/a> ha decidido introducir el sistema de gesti\u00f3n de franjas horarias <a href=\"https:\/\/start.cargoclix.com\/es\/slot\/\" target=\"_blank\" rel=\"noopener noreferrer\">SLOT<\/a> de Cargoclix en Norderstedt cerca de Hamburgo. En dos rampas de la zona de recepci\u00f3n de mercanc\u00edas, los camiones se manejan sin problemas con la ayuda del sistema. Las franjas horarias electr\u00f3nicamente reservables pueden ser reservadas con un mes de anticipaci\u00f3n. Las reservas en la conferencia antes de la entrega son posibles hasta las 4 pm. Un proceso de reserva cuesta 50 c\u00e9ntimos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">D.F. Liedelt Heizungs- und Sanit\u00e4r Gro\u00dfhandels-GmbH forma parte del grupo Paulsen desde 2002. Se apoya sobre tres columnas: Andreas Paulsen en Schleswig-Holstein, D.F. se instala en la zona de Hamburgo y el norte de Baja Sajonia y Paulsen &amp; Eckhardt en Mecklemburgo-Pomerania Occidental y Brandenburgo. El Grupo Paulsen almacena m\u00e1s de 25.000 art\u00edculos diferentes en sus almacenes centrales y alrededor de 5.000 art\u00edculos en cada centro de recogida.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-10350\" src=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png\" alt=\"Andreas Paulsen\" width=\"448\" height=\"112\" srcset=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png 448w, https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen-300x75.png 300w, https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen-224x56.png 224w\" sizes=\"(max-width: 448px) 100vw, 448px\" \/><\/a><\/span><\/p>\n<p><a href=\"https:\/\/start.cargoclix.com\/es\/slot\/\"><span style=\"font-weight: 400;\">*Cargoclix SLOT. Gesti\u00f3n de franjas horarias y patios<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Cargoclix SLOT optimiza los procesos y el despliegue de personal en la rampa. Evita tiempos de espera y los picos en los puntos de carga y descarga.\u00a0 Nuestro sistema de gesti\u00f3n de franjas horarias tambi\u00e9n garantiza la transparencia de todos los procesos log\u00edsticos. Por lo tanto, es la mejor soluci\u00f3n para la industria, el comercio, los proveedores de servicios log\u00edsticos y las empresas de transporte.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D.F. Liedelt Heizungs- und Sanit\u00e4r Gro\u00dfhandels-GmbH ha decidido introducir el sistema de gesti\u00f3n de franjas horarias SLOT de Cargoclix en Norderstedt cerca de Hamburgo. En dos rampas de la zona de recepci\u00f3n de mercanc\u00edas, los camiones se manejan sin problemas con la ayuda del sistema. Las franjas horarias electr\u00f3nicamente reservables pueden ser reservadas con un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[331,292],"tags":[335],"class_list":["post-10365","post","type-post","status-publish","format-standard","hentry","category-company-news-es","category-slot-news-es","tag-slot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El mayorista D. F. Liedelt presenta SLOT - Cargoclix<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mayorista D. F. Liedelt presenta SLOT - Cargoclix\" \/>\n<meta property=\"og:description\" content=\"D.F. Liedelt Heizungs- und Sanit\u00e4r Gro\u00dfhandels-GmbH ha decidido introducir el sistema de gesti\u00f3n de franjas horarias SLOT de Cargoclix en Norderstedt cerca de Hamburgo. En dos rampas de la zona de recepci\u00f3n de mercanc\u00edas, los camiones se manejan sin problemas con la ayuda del sistema. Las franjas horarias electr\u00f3nicamente reservables pueden ser reservadas con un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/\" \/>\n<meta property=\"og:site_name\" content=\"Cargoclix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/cargoclix\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-25T10:07:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png\" \/>\n<meta name=\"author\" content=\"websitedev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"websitedev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/\"},\"author\":{\"name\":\"websitedev\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\"},\"headline\":\"El mayorista D. F. Liedelt presenta SLOT\",\"datePublished\":\"2019-09-25T10:07:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/\"},\"wordCount\":245,\"publisher\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png\",\"keywords\":[\"SLOT\"],\"articleSection\":[\"Company News\",\"SLOT News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/\",\"url\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/\",\"name\":\"El mayorista D. F. Liedelt presenta SLOT - Cargoclix\",\"isPartOf\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png\",\"datePublished\":\"2019-09-25T10:07:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#primaryimage\",\"url\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png\",\"contentUrl\":\"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/start.cargoclix.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Company News\",\"item\":\"https:\/\/start.cargoclix.com\/es\/category\/company-news-es\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SLOT News\",\"item\":\"https:\/\/start.cargoclix.com\/es\/category\/company-news-es\/slot-news-es\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"El mayorista D. F. Liedelt presenta SLOT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#website\",\"url\":\"https:\/\/start.cargoclix.com\/ru\/\",\"name\":\"Cargoclix\",\"description\":\"The logistics platform\",\"publisher\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/start.cargoclix.com\/ru\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#organization\",\"name\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\",\"url\":\"https:\/\/start.cargoclix.com\/ru\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"contentUrl\":\"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png\",\"width\":717,\"height\":214,\"caption\":\"CARGOCLIX Dr. Meier & Schmidt GmbH\"},\"image\":{\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/web.facebook.com\/cargoclix\/\",\"https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh\",\"https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0\",\"name\":\"websitedev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g\",\"caption\":\"websitedev\"},\"url\":\"https:\/\/start.cargoclix.com\/es\/author\/websitedev\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mayorista D. F. Liedelt presenta SLOT - Cargoclix","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/","og_locale":"es_ES","og_type":"article","og_title":"El mayorista D. F. Liedelt presenta SLOT - Cargoclix","og_description":"D.F. Liedelt Heizungs- und Sanit\u00e4r Gro\u00dfhandels-GmbH ha decidido introducir el sistema de gesti\u00f3n de franjas horarias SLOT de Cargoclix en Norderstedt cerca de Hamburgo. En dos rampas de la zona de recepci\u00f3n de mercanc\u00edas, los camiones se manejan sin problemas con la ayuda del sistema. Las franjas horarias electr\u00f3nicamente reservables pueden ser reservadas con un [&hellip;]","og_url":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/","og_site_name":"Cargoclix","article_publisher":"https:\/\/web.facebook.com\/cargoclix\/","article_published_time":"2019-09-25T10:07:40+00:00","og_image":[{"url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png","type":"","width":"","height":""}],"author":"websitedev","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"websitedev","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#article","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/"},"author":{"name":"websitedev","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0"},"headline":"El mayorista D. F. Liedelt presenta SLOT","datePublished":"2019-09-25T10:07:40+00:00","mainEntityOfPage":{"@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/"},"wordCount":245,"publisher":{"@id":"https:\/\/start.cargoclix.com\/ru\/#organization"},"image":{"@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png","keywords":["SLOT"],"articleSection":["Company News","SLOT News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/","url":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/","name":"El mayorista D. F. Liedelt presenta SLOT - Cargoclix","isPartOf":{"@id":"https:\/\/start.cargoclix.com\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#primaryimage"},"image":{"@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#primaryimage"},"thumbnailUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png","datePublished":"2019-09-25T10:07:40+00:00","breadcrumb":{"@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#primaryimage","url":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png","contentUrl":"https:\/\/start.cargoclix.com\/wp-content\/uploads\/2019\/09\/Andreas-Paulsen.png"},{"@type":"BreadcrumbList","@id":"https:\/\/start.cargoclix.com\/es\/2019\/09\/25\/el-mayorista-d-f-liedelt-presenta-slot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/start.cargoclix.com\/es\/"},{"@type":"ListItem","position":2,"name":"Company News","item":"https:\/\/start.cargoclix.com\/es\/category\/company-news-es\/"},{"@type":"ListItem","position":3,"name":"SLOT News","item":"https:\/\/start.cargoclix.com\/es\/category\/company-news-es\/slot-news-es\/"},{"@type":"ListItem","position":4,"name":"El mayorista D. F. Liedelt presenta SLOT"}]},{"@type":"WebSite","@id":"https:\/\/start.cargoclix.com\/ru\/#website","url":"https:\/\/start.cargoclix.com\/ru\/","name":"Cargoclix","description":"The logistics platform","publisher":{"@id":"https:\/\/start.cargoclix.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/start.cargoclix.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/start.cargoclix.com\/ru\/#organization","name":"CARGOCLIX Dr. Meier & Schmidt GmbH","url":"https:\/\/start.cargoclix.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","contentUrl":"https:\/\/w.cargoclix.de\/wp-content\/uploads\/2019\/09\/cargoclix-logo.png","width":717,"height":214,"caption":"CARGOCLIX Dr. Meier & Schmidt GmbH"},"image":{"@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/cargoclix\/","https:\/\/www.linkedin.com\/company\/cargoclix-dr.-meier-&amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;amp;-schmidt-gmbh","https:\/\/www.youtube.com\/channel\/UCc-a2T_VMYfiSYkms8roDug"]},{"@type":"Person","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/761583d14e463481caff5725b4be04f0","name":"websitedev","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/start.cargoclix.com\/ru\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c743e2b237fb238c9113cd949a1e9a3d577059eb66e1d86b608919c637c834e6?s=96&d=mm&r=g","caption":"websitedev"},"url":"https:\/\/start.cargoclix.com\/es\/author\/websitedev\/"}]}},"_links":{"self":[{"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/posts\/10365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/comments?post=10365"}],"version-history":[{"count":0,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/posts\/10365\/revisions"}],"wp:attachment":[{"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/media?parent=10365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/categories?post=10365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/start.cargoclix.com\/es\/wp-json\/wp\/v2\/tags?post=10365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}